{"id":59695,"date":"2024-06-24T08:05:46","date_gmt":"2024-06-24T08:05:46","guid":{"rendered":"https:\/\/pozza1865.com\/portfolio-articoli\/parco-giochi-fantasy-286mq\/"},"modified":"2024-08-01T10:49:54","modified_gmt":"2024-08-01T10:49:54","slug":"parco-giochi-fantasy-286mq","status":"publish","type":"portfolio","link":"https:\/\/www.pozza.it\/en\/portfolio-articoli\/parco-giochi-fantasy-286mq\/","title":{"rendered":"286 mq"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4gb7wya-06a6523ed907aa70306e22f294caf58e\">\n#top .hr.hr-invisible.av-4gb7wya-06a6523ed907aa70306e22f294caf58e{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-4gb7wya-06a6523ed907aa70306e22f294caf58e hr-invisible  avia-builder-el-0  el_before_av_textblock  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lw7lzdri-13fe47652b2b1a8b7329117b25f37156\">\n#top .av_textblock_section.av-lw7lzdri-13fe47652b2b1a8b7329117b25f37156 .avia_textblock{\ncolor:#f09135;\n}\n<\/style>\n<section  class='av_textblock_section av-lw7lzdri-13fe47652b2b1a8b7329117b25f37156 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><h1 style=\"text-align: left;\">Parco giochi outdoor &#8211; Fantasy 286mq.<\/h1>\n<\/div><\/section>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4dhffnm-404640c81000c37d76bdffd5c5a04439\">\n.avia-section.av-4dhffnm-404640c81000c37d76bdffd5c5a04439 .av-parallax .av-parallax-inner{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-4.webp);\nbackground-position:50% 100%;\nbackground-attachment:scroll;\n}\n.avia-section.av-4dhffnm-404640c81000c37d76bdffd5c5a04439 .av-section-color-overlay{\nopacity:0.3;\nbackground-color:#b0cb52;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-4dhffnm-404640c81000c37d76bdffd5c5a04439 main_color avia-section-default avia-no-border-styling  avia-builder-el-2  el_after_av_textblock  el_before_av_section  avia-full-stretch av-parallax-section avia-bg-style-parallax av-section-color-overlay-active av-minimum-height av-minimum-height-50 av-height-50  container_wrap fullsize'  data-section-bg-repeat='stretch' data-av_minimum_height_pc='50' data-av_min_height_opt='50'><div class='av-parallax' data-avia-parallax-ratio='0.3' ><div class='av-parallax-inner main_color avia-full-stretch'><\/div><\/div><div class=\"av-section-color-overlay-wrap\"><div class=\"av-section-color-overlay\"><\/div><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-59695'><div class='entry-content-wrapper clearfix'>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><\/div><div id='produzione'  class='avia-section av-4cc1t42-b1e67241a5cb8e633688254e0b382a99 main_color avia-section-default avia-no-border-styling  avia-builder-el-3  el_after_av_section  el_before_av_section  avia-bg-style-scroll av-minimum-height av-minimum-height-75 av-height-75  container_wrap fullsize'   data-av_minimum_height_pc='75' data-av_min_height_opt='75'><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-59695'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4b5ebc2-562173e3f3d43718a1832baca730bc42\">\n#top .hr.hr-invisible.av-4b5ebc2-562173e3f3d43718a1832baca730bc42{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-4b5ebc2-562173e3f3d43718a1832baca730bc42 hr-invisible  avia-builder-el-4  el_before_av_one_third  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div class='flex_column_table av-48qmtci-2f17b28143b4f1d02556648f28490629 sc-av_one_third av-equal-height-column-flextable'><div  class='flex_column av-48qmtci-2f17b28143b4f1d02556648f28490629 av_one_third  avia-builder-el-5  el_after_av_hr  el_before_av_one_third  first flex_column_table_cell av-equal-height-column av-align-top av-animated-generic bottom-to-top  '     ><section  class='av_textblock_section av-4793376-978399409f1648d97805b7b33eff2c2e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 class=\"p1\">Parco giochi completo outdoor.<br \/>\n&#8211; 286 mq<br \/>\n&#8211; 7 divertimenti<br \/>\n&#8211; pavimento antitrauma<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-45r4kn6-54e82c6549f7a5777a5b05724beddf08\">\n#top .hr.av-45r4kn6-54e82c6549f7a5777a5b05724beddf08{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-45r4kn6-54e82c6549f7a5777a5b05724beddf08 .hr-inner{\nwidth:30%;\nborder-color:#f09135;\n}\n<\/style>\n<div  class='hr av-45r4kn6-54e82c6549f7a5777a5b05724beddf08 hr-custom  avia-builder-el-7  el_after_av_textblock  avia-builder-el-last  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-4464bgy-dbcdff4a8d089ab04e91b30991572034 av_one_third  avia-builder-el-8  el_after_av_one_third  el_before_av_one_third  flex_column_table_cell av-equal-height-column av-align-top av-animated-generic bottom-to-top  '     ><section  class='av_textblock_section av-41pudlu-88ba3f927735df50d1278a726af257a2 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>A &#8211; TORRE DI BABELE BABY LEAVES<\/strong><br \/>\nAF102SSUB.P-2 style LEAVES<\/p>\n<p><strong>B &#8211; SATURNO INCLUSIVE CON SCALA E SCIVOLO LEAVES<\/strong><br \/>\nAF300H.S1-14 style LEAVES<\/p>\n<p><strong>C &#8211; PERCORSO EQUILIBRIO AVVENTURA BABY LEAVES<\/strong><br \/>\n+ PANNELLO MUSICALE +PANNELLO OPTICAL<br \/>\nU0100.T-9 style LEAVES<\/p>\n<p><strong>D &#8211; ALTALENA NIDO + INCLUSIVE ALLU-MINIO<\/strong><br \/>\nB0400ALU.PZ028<\/p>\n<\/div><\/section><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-40bzr4i-02b996ac0675a7375afdb57adb8d5834 av_one_third  avia-builder-el-10  el_after_av_one_third  el_before_av_hr  flex_column_table_cell av-equal-height-column av-align-top av-animated-generic bottom-to-top  '     ><section  class='av_textblock_section av-lxsp6twq-45afec5f622053353b43e16de6f6e33d '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>E &#8211; GIOCO A MOLLA FIGURA DOPPIA GORILLA<\/strong><br \/>\nJ02002<\/p>\n<p><strong>F &#8211; GIRAFFA<\/strong><br \/>\nJ01002<\/p>\n<p><strong>G &#8211; PINBALL<\/strong><br \/>\nU0400.P-7<\/p>\n<\/div><\/section><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-fv21u-e177526fcb8cd1559ff510a01b423953\">\n#top .hr.hr-invisible.av-fv21u-e177526fcb8cd1559ff510a01b423953{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-fv21u-e177526fcb8cd1559ff510a01b423953 hr-invisible  avia-builder-el-12  el_after_av_one_third  el_before_av_one_half '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div class='flex_column_table av-3nyfdf6-353af6c4615a63fdf221baa852e15db5 sc-av_one_half av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3nyfdf6-353af6c4615a63fdf221baa852e15db5\">\n.flex_column.av-3nyfdf6-353af6c4615a63fdf221baa852e15db5{\nwidth:49%;\nmargin-left:0;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-3nyfdf6-353af6c4615a63fdf221baa852e15db5 .av-flex-placeholder{\nwidth:2%;\n}\n<\/style>\n<div  class='flex_column av-3nyfdf6-353af6c4615a63fdf221baa852e15db5 av_one_half  avia-builder-el-13  el_after_av_hr  el_before_av_one_half  first flex_column_table_cell av-equal-height-column av-align-top av-animated-generic bottom-to-top  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lw7n9ojy-dab61fa5c89691e9f5eebbccfddab1c9\">\n.avia-image-container.av-lw7n9ojy-dab61fa5c89691e9f5eebbccfddab1c9 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-lw7n9ojy-dab61fa5c89691e9f5eebbccfddab1c9 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-lw7n9ojy-dab61fa5c89691e9f5eebbccfddab1c9 av-styling- avia-align-center  avia-builder-el-14  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img fetchpriority=\"high\" fetchpriority=\"high\" class='wp-image-4951 avia-img-lazy-loading-not-4951 avia_image ' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-4.webp' alt='' title='pozza-progetti-pronti-parco-giochi-186fantasy-4'  height=\"1500\" width=\"2000\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div><div class='av-flex-placeholder'><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3gw24xe-5103d8813ce7954eba10fc934e08f750\">\n.flex_column.av-3gw24xe-5103d8813ce7954eba10fc934e08f750{\nwidth:49%;\nmargin-left:0;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-3gw24xe-5103d8813ce7954eba10fc934e08f750 .av-flex-placeholder{\nwidth:2%;\n}\n<\/style>\n<div  class='flex_column av-3gw24xe-5103d8813ce7954eba10fc934e08f750 av_one_half  avia-builder-el-15  el_after_av_one_half  avia-builder-el-last  flex_column_table_cell av-equal-height-column av-align-top av-animated-generic bottom-to-top  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-cbvd4i-95fc1b3c490719daae5e70a7b99219e6\">\n.avia-image-container.av-cbvd4i-95fc1b3c490719daae5e70a7b99219e6 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-cbvd4i-95fc1b3c490719daae5e70a7b99219e6 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-cbvd4i-95fc1b3c490719daae5e70a7b99219e6 av-styling- avia-align-center  avia-builder-el-16  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img fetchpriority=\"high\" fetchpriority=\"high\" class='wp-image-4949 avia-img-lazy-loading-not-4949 avia_image ' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-5.webp' alt='' title='pozza-progetti-pronti-parco-giochi-186fantasy-5'  height=\"1200\" width=\"1800\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ay04l2-30301fae342fb1875027851b407159fc\">\n.avia-section.av-ay04l2-30301fae342fb1875027851b407159fc{\nbackground-color:#a6b8b2;\nbackground:linear-gradient( to bottom, #a6b8b2, #ffffff );\n}\n<\/style>\n<div id='innovazione'  class='avia-section av-ay04l2-30301fae342fb1875027851b407159fc main_color avia-section-default avia-no-border-styling  avia-builder-el-17  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll av-minimum-height av-minimum-height-75 av-height-75  container_wrap fullsize'   data-av_minimum_height_pc='75' data-av_min_height_opt='75'><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-59695'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-z2yjq-d2508170303cd50a1a838e688bceaa8b\">\n.flex_column.av-z2yjq-d2508170303cd50a1a838e688bceaa8b{\nwidth:47%;\nborder-radius:30px 30px 30px 30px;\npadding:30px 30px 30px 30px;\nbackground-color:#eceded;\n}\n<\/style>\n<div  class='flex_column av-z2yjq-d2508170303cd50a1a838e688bceaa8b av_one_half  avia-builder-el-18  el_before_av_one_half  avia-builder-el-first  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7ktcee-4078558f7d66528b43a1d724486ebadd\">\n#top .hr.av-7ktcee-4078558f7d66528b43a1d724486ebadd{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-7ktcee-4078558f7d66528b43a1d724486ebadd .hr-inner{\nwidth:30%;\nborder-color:#f09135;\n}\n<\/style>\n<div  class='hr av-7ktcee-4078558f7d66528b43a1d724486ebadd hr-custom  avia-builder-el-19  el_before_av_textblock  avia-builder-el-first  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-lxsml0yz-d01c3dd0c54d9ab90016fee535210483 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: left;\">Video<\/h2>\n<\/div><\/section><br \/>\n<div  class='avia-video av-lxsmn6ql-a50bfb0b7ebbf61af200ace1ab8e8db9 avia-video-16-9 av-no-preview-image avia-video-load-always avia-video-html5'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/pozza.it\/wp-content\/uploads\/2024\/06\/Pozza_fantasy_286mq.mp4'><video class='avia_video'    preload=\"auto\"  controls id='player_59695_2062363200_1962639068'><source src='https:\/\/pozza.it\/wp-content\/uploads\/2024\/06\/Pozza_fantasy_286mq.mp4' type='video\/mp4' \/><\/video><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5tljdy-1017247b119cb63ad64c184f91e2248a\">\n.flex_column.av-5tljdy-1017247b119cb63ad64c184f91e2248a{\nwidth:47%;\nmargin-left:6%;\nborder-radius:30px 30px 30px 30px;\npadding:30px 30px 30px 30px;\nbackground-color:#eceded;\n}\n<\/style>\n<div  class='flex_column av-5tljdy-1017247b119cb63ad64c184f91e2248a av_one_half  avia-builder-el-22  el_after_av_one_half  avia-builder-el-last  flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3ueb5i-862c87bffc0ed27f5cb8cda2f28fa35f\">\n#top .hr.av-3ueb5i-862c87bffc0ed27f5cb8cda2f28fa35f{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-3ueb5i-862c87bffc0ed27f5cb8cda2f28fa35f .hr-inner{\nwidth:30%;\nborder-color:#f09135;\n}\n<\/style>\n<div  class='hr av-3ueb5i-862c87bffc0ed27f5cb8cda2f28fa35f hr-custom  avia-builder-el-23  el_before_av_textblock  avia-builder-el-first  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-146hi-14380d937d0674c32a5de57307c35ef8 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: left;\">Dettagli parco giochi<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2yvlaq-675178683f68d7d0d4abb6546413d6fe\">\n#top .avia-gallery.av-2yvlaq-675178683f68d7d0d4abb6546413d6fe .avia-gallery-thumb a{\nwidth:50%;\n}\n<\/style>\n<div  class='avia-gallery av-2yvlaq-675178683f68d7d0d4abb6546413d6fe avia_animate_when_visible  avia-builder-el-25  el_after_av_textblock  avia-builder-el-last  animations_off avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/www.pozza.it\/en\/portfolio-articoli\/parco-giochi-fantasy-286mq\/\"><div class='avia-gallery-thumb'><a href=\"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-1-1030x773.webp\" data-rel='gallery-1' data-prev-img='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-1-495x400.webp' class='first_thumb lightbox ' data-onclick='1' title='pozza-progetti-pronti-parco-giochi-186fantasy-1'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-4943 avia-img-lazy-loading-not-4943\"   src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-1-300x225.webp' width='300' height='225'  title='pozza-progetti-pronti-parco-giochi-186fantasy-1' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-4943 avia-img-lazy-loading-4943\"  width='495' height='400' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-1-495x400.webp' title='pozza-progetti-pronti-parco-giochi-186fantasy-1' alt='' \/><\/div><\/a><a href=\"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-300-1-1-1030x773.webp\" data-rel='gallery-1' data-prev-img='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-300-1-1-495x400.webp' class='lightbox ' data-onclick='2' title='pozza-progetti-pronti-parco-giochi-300-1'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-4932 avia-img-lazy-loading-not-4932\"   src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-300-1-1-300x225.webp' width='300' height='225'  title='pozza-progetti-pronti-parco-giochi-300-1' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-4932 avia-img-lazy-loading-4932\"  width='495' height='400' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-300-1-1-495x400.webp' title='pozza-progetti-pronti-parco-giochi-300-1' alt='' \/><\/div><\/a><a href=\"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-3-1030x773.webp\" data-rel='gallery-1' data-prev-img='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-3-495x400.webp' class='first_thumb lightbox ' data-onclick='3' title='pozza-progetti-pronti-parco-giochi-186fantasy-3'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-4947 avia-img-lazy-loading-not-4947\"   src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-3-300x225.webp' width='300' height='225'  title='pozza-progetti-pronti-parco-giochi-186fantasy-3' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-4947 avia-img-lazy-loading-4947\"  width='495' height='400' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-3-495x400.webp' title='pozza-progetti-pronti-parco-giochi-186fantasy-3' alt='' \/><\/div><\/a><a href=\"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-2-1030x773.webp\" data-rel='gallery-1' data-prev-img='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-2-495x400.webp' class='lightbox ' data-onclick='4' title='pozza-progetti-pronti-parco-giochi-186fantasy-2'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-4945 avia-img-lazy-loading-not-4945\"   src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-2-300x225.webp' width='300' height='225'  title='pozza-progetti-pronti-parco-giochi-186fantasy-2' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-4945 avia-img-lazy-loading-4945\"  width='495' height='400' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-2-495x400.webp' title='pozza-progetti-pronti-parco-giochi-186fantasy-2' alt='' \/><\/div><\/a><\/div><\/div><\/p><\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OUTDOOR FANTASY<br \/>\n286 MQ<\/p>\n","protected":false},"author":1,"featured_media":4951,"template":"","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"portfolio_entries":[1064,1066],"class_list":["post-59695","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-outdoor","portfolio_entries-public-structures"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>286 mq - Pozza 1865<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-fantasy-286mq\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"286 mq - Pozza 1865\" \/>\n<meta property=\"og:description\" content=\"OUTDOOR FANTASY 286 MQ\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-fantasy-286mq\/\" \/>\n<meta property=\"og:site_name\" content=\"Pozza 1865\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pozza.it\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-01T10:49:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-4.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"31 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-fantasy-286mq\\\/\",\"url\":\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-fantasy-286mq\\\/\",\"name\":\"286 mq - Pozza 1865\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pozza.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-fantasy-286mq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-fantasy-286mq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pozza.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/pozza-progetti-pronti-parco-giochi-186fantasy-4.webp\",\"datePublished\":\"2024-06-24T08:05:46+00:00\",\"dateModified\":\"2024-08-01T10:49:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-fantasy-286mq\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-fantasy-286mq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-fantasy-286mq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pozza.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/pozza-progetti-pronti-parco-giochi-186fantasy-4.webp\",\"contentUrl\":\"https:\\\/\\\/www.pozza.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/pozza-progetti-pronti-parco-giochi-186fantasy-4.webp\",\"width\":2000,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-fantasy-286mq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pozza.it\\\/en\\\/pozza-playground-games-and-park-equipment-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"286 mq\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pozza.it\\\/#website\",\"url\":\"https:\\\/\\\/www.pozza.it\\\/\",\"name\":\"www.pozza.it\",\"description\":\"giochi e attrezzature per parcho giochi | playground equipment\",\"alternateName\":\"pozza 1865\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pozza.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"286 mq - Pozza 1865","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-fantasy-286mq\/","og_locale":"en_US","og_type":"article","og_title":"286 mq - Pozza 1865","og_description":"OUTDOOR FANTASY 286 MQ","og_url":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-fantasy-286mq\/","og_site_name":"Pozza 1865","article_publisher":"https:\/\/www.facebook.com\/pozza.it\/","article_modified_time":"2024-08-01T10:49:54+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-4.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"31 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-fantasy-286mq\/","url":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-fantasy-286mq\/","name":"286 mq - Pozza 1865","isPartOf":{"@id":"https:\/\/www.pozza.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-fantasy-286mq\/#primaryimage"},"image":{"@id":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-fantasy-286mq\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-4.webp","datePublished":"2024-06-24T08:05:46+00:00","dateModified":"2024-08-01T10:49:54+00:00","breadcrumb":{"@id":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-fantasy-286mq\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-fantasy-286mq\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-fantasy-286mq\/#primaryimage","url":"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-4.webp","contentUrl":"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/06\/pozza-progetti-pronti-parco-giochi-186fantasy-4.webp","width":2000,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-fantasy-286mq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pozza.it\/en\/pozza-playground-games-and-park-equipment-2\/"},{"@type":"ListItem","position":2,"name":"286 mq"}]},{"@type":"WebSite","@id":"https:\/\/www.pozza.it\/#website","url":"https:\/\/www.pozza.it\/","name":"www.pozza.it","description":"giochi e attrezzature per parcho giochi | playground equipment","alternateName":"pozza 1865","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pozza.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/portfolio\/59695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/portfolio\/59695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/media\/4951"}],"wp:attachment":[{"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/media?parent=59695"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/tags?post=59695"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/portfolio_entries?post=59695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}