{"id":59683,"date":"2024-05-15T09:18:03","date_gmt":"2024-05-15T09:18:03","guid":{"rendered":"https:\/\/pozza1865.com\/portfolio-articoli\/parco-giochi-203mq\/"},"modified":"2024-08-01T10:49:01","modified_gmt":"2024-08-01T10:49:01","slug":"parco-giochi-203mq","status":"publish","type":"portfolio","link":"https:\/\/www.pozza.it\/en\/portfolio-articoli\/parco-giochi-203mq\/","title":{"rendered":"203 mq"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4gb7wya-06a6523ed907aa70306e22f294caf58e\">\n#top .hr.hr-invisible.av-4gb7wya-06a6523ed907aa70306e22f294caf58e{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-4gb7wya-06a6523ed907aa70306e22f294caf58e hr-invisible  avia-builder-el-0  el_before_av_textblock  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lw7lzdri-13fe47652b2b1a8b7329117b25f37156\">\n#top .av_textblock_section.av-lw7lzdri-13fe47652b2b1a8b7329117b25f37156 .avia_textblock{\ncolor:#f09135;\n}\n<\/style>\n<section  class='av_textblock_section av-lw7lzdri-13fe47652b2b1a8b7329117b25f37156 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><h1 style=\"text-align: left;\">Parco giochi outdoor &#8211; 203mq.<\/h1>\n<\/div><\/section>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4dhffnm-0d20602cff7027cef786749ed0ed04bd\">\n.avia-section.av-4dhffnm-0d20602cff7027cef786749ed0ed04bd .av-parallax .av-parallax-inner{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-13-.webp);\nbackground-position:50% 100%;\nbackground-attachment:scroll;\n}\n.avia-section.av-4dhffnm-0d20602cff7027cef786749ed0ed04bd .av-section-color-overlay{\nopacity:0.3;\nbackground-color:#b0cb52;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-4dhffnm-0d20602cff7027cef786749ed0ed04bd main_color avia-section-default avia-no-border-styling  avia-builder-el-2  el_after_av_textblock  el_before_av_section  avia-full-stretch av-parallax-section avia-bg-style-parallax av-section-color-overlay-active av-minimum-height av-minimum-height-50 av-height-50  container_wrap fullsize'  data-section-bg-repeat='stretch' data-av_minimum_height_pc='50' data-av_min_height_opt='50'><div class='av-parallax' data-avia-parallax-ratio='0.3' ><div class='av-parallax-inner main_color avia-full-stretch'><\/div><\/div><div class=\"av-section-color-overlay-wrap\"><div class=\"av-section-color-overlay\"><\/div><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-59683'><div class='entry-content-wrapper clearfix'>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><\/div><div id='produzione'  class='avia-section av-4cc1t42-b1e67241a5cb8e633688254e0b382a99 main_color avia-section-default avia-no-border-styling  avia-builder-el-3  el_after_av_section  el_before_av_section  avia-bg-style-scroll av-minimum-height av-minimum-height-75 av-height-75  container_wrap fullsize'   data-av_minimum_height_pc='75' data-av_min_height_opt='75'><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-59683'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4b5ebc2-562173e3f3d43718a1832baca730bc42\">\n#top .hr.hr-invisible.av-4b5ebc2-562173e3f3d43718a1832baca730bc42{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-4b5ebc2-562173e3f3d43718a1832baca730bc42 hr-invisible  avia-builder-el-4  el_before_av_one_third  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div class='flex_column_table av-48qmtci-2f17b28143b4f1d02556648f28490629 sc-av_one_third av-equal-height-column-flextable'><div  class='flex_column av-48qmtci-2f17b28143b4f1d02556648f28490629 av_one_third  avia-builder-el-5  el_after_av_hr  el_before_av_one_third  first flex_column_table_cell av-equal-height-column av-align-top av-animated-generic bottom-to-top  '     ><section  class='av_textblock_section av-4793376-978399409f1648d97805b7b33eff2c2e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 class=\"p1\">Parco giochi completo outdoor.<br \/>\n&#8211; 203 mq<br \/>\n&#8211; 7 divertimenti<br \/>\n&#8211; pavimento antitrauma<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-45r4kn6-54e82c6549f7a5777a5b05724beddf08\">\n#top .hr.av-45r4kn6-54e82c6549f7a5777a5b05724beddf08{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-45r4kn6-54e82c6549f7a5777a5b05724beddf08 .hr-inner{\nwidth:30%;\nborder-color:#f09135;\n}\n<\/style>\n<div  class='hr av-45r4kn6-54e82c6549f7a5777a5b05724beddf08 hr-custom  avia-builder-el-7  el_after_av_textblock  avia-builder-el-last  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-4464bgy-dbcdff4a8d089ab04e91b30991572034 av_one_third  avia-builder-el-8  el_after_av_one_third  el_before_av_one_third  flex_column_table_cell av-equal-height-column av-align-top av-animated-generic bottom-to-top  '     ><section  class='av_textblock_section av-41pudlu-88ba3f927735df50d1278a726af257a2 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>A &#8211; ALTALENA NIDO DOPPIA ALLUMINIO<br \/>\n<\/strong>B0400.2 style ALU<\/p>\n<p><strong>B &#8211; GIOCO A MOLLA FIGURA DOPPIA BALENA<br \/>\nJ02003<\/strong><\/p>\n<p><strong>C &#8211; GIOSTRA GIROTONDO INCLUSIVE<br \/>\nG0300H1<\/strong><\/p>\n<p><strong>D &#8211; SATURNO CON PONTE FISSO ALLUMINIO<\/strong><br \/>\nAF300H.PI-11 style ALU<\/p>\n<\/div><\/section><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-40bzr4i-02b996ac0675a7375afdb57adb8d5834 av_one_third  avia-builder-el-10  el_after_av_one_third  el_before_av_hr  flex_column_table_cell av-equal-height-column av-align-top av-animated-generic bottom-to-top  '     ><section  class='av_textblock_section av-3z1rnpu-ffa2f97f6e1793621861e3b583b7aebb '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>E &#8211; PANNELLI MUSICALI INTERATTIVI ALLUMINIO<br \/>\n<\/strong>U0600-N.BV-7ALU<\/p>\n<p><strong>F &#8211; DONDOLO INCLUSIVE<br \/>\n<\/strong>F0800H<\/p>\n<p><strong>G &#8211; GIOCO A MOLLA FIGURA DOPPIA LEONE<\/strong><br \/>\nJ02001<\/p>\n<p><strong>PAVIMENTO<\/strong><br \/>\nCOLATO IN OPERA PAVCOLATA 203 m2<\/p>\n<\/div><\/section><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-fv21u-e177526fcb8cd1559ff510a01b423953\">\n#top .hr.hr-invisible.av-fv21u-e177526fcb8cd1559ff510a01b423953{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-fv21u-e177526fcb8cd1559ff510a01b423953 hr-invisible  avia-builder-el-12  el_after_av_one_third  el_before_av_one_half '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div class='flex_column_table av-3nyfdf6-353af6c4615a63fdf221baa852e15db5 sc-av_one_half av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3nyfdf6-353af6c4615a63fdf221baa852e15db5\">\n.flex_column.av-3nyfdf6-353af6c4615a63fdf221baa852e15db5{\nwidth:49%;\nmargin-left:0;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-3nyfdf6-353af6c4615a63fdf221baa852e15db5 .av-flex-placeholder{\nwidth:2%;\n}\n<\/style>\n<div  class='flex_column av-3nyfdf6-353af6c4615a63fdf221baa852e15db5 av_one_half  avia-builder-el-13  el_after_av_hr  el_before_av_one_half  first flex_column_table_cell av-equal-height-column av-align-top av-animated-generic bottom-to-top  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lw7n9ojy-b33f51b489e5c65c60c237c193319cbe\">\n.avia-image-container.av-lw7n9ojy-b33f51b489e5c65c60c237c193319cbe img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-lw7n9ojy-b33f51b489e5c65c60c237c193319cbe .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-lw7n9ojy-b33f51b489e5c65c60c237c193319cbe av-styling- avia-align-center  avia-builder-el-14  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img fetchpriority=\"high\" fetchpriority=\"high\" class='wp-image-3163 avia-img-lazy-loading-not-3163 avia_image ' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-13-.webp' alt='' title='parco_giochi-pozza-forli\u0300-13'  height=\"1049\" width=\"1500\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div><div class='av-flex-placeholder'><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3gw24xe-5103d8813ce7954eba10fc934e08f750\">\n.flex_column.av-3gw24xe-5103d8813ce7954eba10fc934e08f750{\nwidth:49%;\nmargin-left:0;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-3gw24xe-5103d8813ce7954eba10fc934e08f750 .av-flex-placeholder{\nwidth:2%;\n}\n<\/style>\n<div  class='flex_column av-3gw24xe-5103d8813ce7954eba10fc934e08f750 av_one_half  avia-builder-el-15  el_after_av_one_half  avia-builder-el-last  flex_column_table_cell av-equal-height-column av-align-top av-animated-generic bottom-to-top  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-cbvd4i-a041b56ee600da2540af998966d99a53\">\n.avia-image-container.av-cbvd4i-a041b56ee600da2540af998966d99a53 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-cbvd4i-a041b56ee600da2540af998966d99a53 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-cbvd4i-a041b56ee600da2540af998966d99a53 av-styling- avia-align-center  avia-builder-el-16  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img fetchpriority=\"high\" fetchpriority=\"high\" class='wp-image-3185 avia-img-lazy-loading-not-3185 avia_image ' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-08-.webp' alt='' title='parco_giochi-pozza-forli\u0300-08'  height=\"1228\" width=\"1842\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3qniygy-1c8863ac478910b88896b0ba6bce5c05\">\n.avia-section.av-3qniygy-1c8863ac478910b88896b0ba6bce5c05{\nbackground-color:#a6b8b2;\nbackground:linear-gradient( to bottom, #a6b8b2, #ffffff );\n}\n<\/style>\n<div id='innovazione'  class='avia-section av-3qniygy-1c8863ac478910b88896b0ba6bce5c05 main_color avia-section-default avia-no-border-styling  avia-builder-el-17  el_after_av_section  el_before_av_hr  avia-bg-style-scroll av-minimum-height av-minimum-height-75 av-height-75  container_wrap fullsize'   data-av_minimum_height_pc='75' data-av_min_height_opt='75'><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-59683'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column_table av-7ae0ia-901deaf77ee56f5c68facd70487561b3 sc-av_one_half av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7ae0ia-901deaf77ee56f5c68facd70487561b3\">\n.flex_column.av-7ae0ia-901deaf77ee56f5c68facd70487561b3{\nwidth:47%;\nmargin-left:0;\nborder-radius:30px 30px 30px 30px;\npadding:30px 30px 30px 30px;\nbackground-color:#eceded;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-7ae0ia-901deaf77ee56f5c68facd70487561b3 .av-flex-placeholder{\nwidth:6%;\n}\n<\/style>\n<div  class='flex_column av-7ae0ia-901deaf77ee56f5c68facd70487561b3 av_one_half  avia-builder-el-18  el_before_av_one_half  avia-builder-el-first  first flex_column_table_cell av-equal-height-column av-align-top  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-iq5gy-698316819b50daf3ffc81d5a92c3da7c\">\n#top .hr.av-iq5gy-698316819b50daf3ffc81d5a92c3da7c{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-iq5gy-698316819b50daf3ffc81d5a92c3da7c .hr-inner{\nwidth:30%;\nborder-color:#f09135;\n}\n<\/style>\n<div  class='hr av-iq5gy-698316819b50daf3ffc81d5a92c3da7c hr-custom  avia-builder-el-19  el_before_av_textblock  avia-builder-el-first  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-3x234y-140c44e255cc723eb6c1ac4f55201969 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: left;\">Modello 3D<\/h2>\n<\/div><\/section><br \/>\n<\/p><\/div><div class='av-flex-placeholder'><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-213102-dadcd0edb9e6395840fd9276b5544099\">\n.flex_column.av-213102-dadcd0edb9e6395840fd9276b5544099{\nwidth:47%;\nmargin-left:0;\nborder-radius:30px 30px 30px 30px;\npadding:30px 30px 30px 30px;\nbackground-color:#eceded;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-213102-dadcd0edb9e6395840fd9276b5544099 .av-flex-placeholder{\nwidth:6%;\n}\n<\/style>\n<div  class='flex_column av-213102-dadcd0edb9e6395840fd9276b5544099 av_one_half  avia-builder-el-22  el_after_av_one_half  avia-builder-el-last  flex_column_table_cell av-equal-height-column av-align-top  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5ftbn6-e36e981287494b36b7a97d8245216067\">\n#top .hr.av-5ftbn6-e36e981287494b36b7a97d8245216067{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-5ftbn6-e36e981287494b36b7a97d8245216067 .hr-inner{\nwidth:30%;\nborder-color:#f09135;\n}\n<\/style>\n<div  class='hr av-5ftbn6-e36e981287494b36b7a97d8245216067 hr-custom  avia-builder-el-23  el_before_av_textblock  avia-builder-el-first  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-4epsxu-7a9a8f6e880dffb2999f97e6e738c10e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: left;\">Dettagli parco giochi<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2yvlaq-f1109a4c501da753c702b2b0227c8a09\">\n#top .avia-gallery.av-2yvlaq-f1109a4c501da753c702b2b0227c8a09 .avia-gallery-thumb a{\nwidth:25%;\n}\n<\/style>\n<div  class='avia-gallery av-2yvlaq-f1109a4c501da753c702b2b0227c8a09 avia_animate_when_visible  avia-builder-el-25  el_after_av_textblock  avia-builder-el-last  animations_off avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/www.pozza.it\/en\/portfolio-articoli\/parco-giochi-203mq\/\"><div class='avia-gallery-thumb'><a href=\"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-01-.webp\" data-rel='gallery-1' data-prev-img='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-01--454x400.webp' class='first_thumb lightbox ' data-onclick='1' title='A'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-3167 avia-img-lazy-loading-not-3167\"  data-avia-tooltip='A' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-01--300x300.webp' width='300' height='300'  title='parco_giochi-pozza-forli\u0300-01' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-3167 avia-img-lazy-loading-3167\"  width='454' height='400' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-01--454x400.webp' title='parco_giochi-pozza-forli\u0300-01' alt='' \/><\/div><\/a><a href=\"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-02-.webp\" data-rel='gallery-1' data-prev-img='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-02--454x400.webp' class='lightbox ' data-onclick='2' title='B'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-3169 avia-img-lazy-loading-not-3169\"  data-avia-tooltip='B' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-02--300x300.webp' width='300' height='300'  title='parco_giochi-pozza-forli\u0300-02' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-3169 avia-img-lazy-loading-3169\"  width='454' height='400' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-02--454x400.webp' title='parco_giochi-pozza-forli\u0300-02' alt='' \/><\/div><\/a><a href=\"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-03-.webp\" data-rel='gallery-1' data-prev-img='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-03--454x400.webp' class='lightbox ' data-onclick='3' title='C'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-3171 avia-img-lazy-loading-not-3171\"  data-avia-tooltip='C' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-03--300x300.webp' width='300' height='300'  title='parco_giochi-pozza-forli\u0300-03' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-3171 avia-img-lazy-loading-3171\"  width='454' height='400' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-03--454x400.webp' title='parco_giochi-pozza-forli\u0300-03' alt='' \/><\/div><\/a><a href=\"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-04-.webp\" data-rel='gallery-1' data-prev-img='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-04--454x400.webp' class='lightbox ' data-onclick='4' title='D'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-3173 avia-img-lazy-loading-not-3173\"  data-avia-tooltip='D' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-04--300x300.webp' width='300' height='300'  title='parco_giochi-pozza-forli\u0300-04' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-3173 avia-img-lazy-loading-3173\"  width='454' height='400' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-04--454x400.webp' title='parco_giochi-pozza-forli\u0300-04' alt='' \/><\/div><\/a><a href=\"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-05-.webp\" data-rel='gallery-1' data-prev-img='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-05--454x400.webp' class='first_thumb lightbox ' data-onclick='5' title='E'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-3175 avia-img-lazy-loading-not-3175\"  data-avia-tooltip='E' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-05--300x300.webp' width='300' height='300'  title='parco_giochi-pozza-forli\u0300-05' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-3175 avia-img-lazy-loading-3175\"  width='454' height='400' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-05--454x400.webp' title='parco_giochi-pozza-forli\u0300-05' alt='' \/><\/div><\/a><a href=\"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-06-.webp\" data-rel='gallery-1' data-prev-img='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-06--454x400.webp' class='lightbox ' data-onclick='6' title='F'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-3177 avia-img-lazy-loading-not-3177\"  data-avia-tooltip='F' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-06--300x300.webp' width='300' height='300'  title='parco_giochi-pozza-forli\u0300-06' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-3177 avia-img-lazy-loading-3177\"  width='454' height='400' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-06--454x400.webp' title='parco_giochi-pozza-forli\u0300-06' alt='' \/><\/div><\/a><a href=\"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-07-.webp\" data-rel='gallery-1' data-prev-img='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-07--454x400.webp' class='lightbox ' data-onclick='7' title='G'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-3179 avia-img-lazy-loading-not-3179\"  data-avia-tooltip='G' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-07--300x300.webp' width='300' height='300'  title='parco_giochi-pozza-forli\u0300-07' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-3179 avia-img-lazy-loading-3179\"  width='454' height='400' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-07--454x400.webp' title='parco_giochi-pozza-forli\u0300-07' alt='' \/><\/div><\/a><a href=\"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-10-1-1.webp\" data-rel='gallery-1' data-prev-img='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-10-1-1-495x400.webp' class='lightbox ' data-onclick='8' title='PAV'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-3281 avia-img-lazy-loading-not-3281\"  data-avia-tooltip='PAV' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-10-1-1-300x300.webp' width='300' height='300'  title='parco_giochi-pozza-forli\u0300-10' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-3281 avia-img-lazy-loading-3281\"  width='495' height='400' src='https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-10-1-1-495x400.webp' title='parco_giochi-pozza-forli\u0300-10' alt='' \/><\/div><\/a><\/div><\/div><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_3'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-59683'><div class='entry-content-wrapper clearfix'><\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2ym5si-cfeb4e3b3354557d01b517d6f6b4fc22\">\n#top .hr.hr-invisible.av-2ym5si-cfeb4e3b3354557d01b517d6f6b4fc22{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-2ym5si-cfeb4e3b3354557d01b517d6f6b4fc22 hr-invisible  avia-builder-el-26  el_after_av_section  avia-builder-el-no-sibling '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>OUTDOOR<br \/>\n203 MQ<\/p>\n","protected":false},"author":1,"featured_media":3163,"template":"","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"portfolio_entries":[1064,1066],"class_list":["post-59683","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-outdoor","portfolio_entries-public-structures"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>203 mq - Pozza 1865<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-203mq\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"203 mq - Pozza 1865\" \/>\n<meta property=\"og:description\" content=\"OUTDOOR 203 MQ\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-203mq\/\" \/>\n<meta property=\"og:site_name\" content=\"Pozza 1865\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pozza.it\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-01T10:49:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-13-.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1049\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-203mq\\\/\",\"url\":\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-203mq\\\/\",\"name\":\"203 mq - Pozza 1865\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pozza.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-203mq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-203mq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pozza.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/parco_giochi-pozza-forli-13-.webp\",\"datePublished\":\"2024-05-15T09:18:03+00:00\",\"dateModified\":\"2024-08-01T10:49:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-203mq\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-203mq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-203mq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pozza.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/parco_giochi-pozza-forli-13-.webp\",\"contentUrl\":\"https:\\\/\\\/www.pozza.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/parco_giochi-pozza-forli-13-.webp\",\"width\":1500,\"height\":1049},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pozza.it\\\/portfolio-articoli\\\/parco-giochi-203mq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pozza.it\\\/en\\\/pozza-playground-games-and-park-equipment-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"203 mq\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pozza.it\\\/#website\",\"url\":\"https:\\\/\\\/www.pozza.it\\\/\",\"name\":\"www.pozza.it\",\"description\":\"giochi e attrezzature per parcho giochi | playground equipment\",\"alternateName\":\"pozza 1865\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pozza.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"203 mq - Pozza 1865","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-203mq\/","og_locale":"en_US","og_type":"article","og_title":"203 mq - Pozza 1865","og_description":"OUTDOOR 203 MQ","og_url":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-203mq\/","og_site_name":"Pozza 1865","article_publisher":"https:\/\/www.facebook.com\/pozza.it\/","article_modified_time":"2024-08-01T10:49:01+00:00","og_image":[{"width":1500,"height":1049,"url":"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-13-.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-203mq\/","url":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-203mq\/","name":"203 mq - Pozza 1865","isPartOf":{"@id":"https:\/\/www.pozza.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-203mq\/#primaryimage"},"image":{"@id":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-203mq\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-13-.webp","datePublished":"2024-05-15T09:18:03+00:00","dateModified":"2024-08-01T10:49:01+00:00","breadcrumb":{"@id":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-203mq\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-203mq\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-203mq\/#primaryimage","url":"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-13-.webp","contentUrl":"https:\/\/www.pozza.it\/wp-content\/uploads\/2024\/05\/parco_giochi-pozza-forli-13-.webp","width":1500,"height":1049},{"@type":"BreadcrumbList","@id":"https:\/\/www.pozza.it\/portfolio-articoli\/parco-giochi-203mq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pozza.it\/en\/pozza-playground-games-and-park-equipment-2\/"},{"@type":"ListItem","position":2,"name":"203 mq"}]},{"@type":"WebSite","@id":"https:\/\/www.pozza.it\/#website","url":"https:\/\/www.pozza.it\/","name":"www.pozza.it","description":"giochi e attrezzature per parcho giochi | playground equipment","alternateName":"pozza 1865","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pozza.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/portfolio\/59683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/portfolio\/59683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/media\/3163"}],"wp:attachment":[{"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/media?parent=59683"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/tags?post=59683"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/www.pozza.it\/en\/wp-json\/wp\/v2\/portfolio_entries?post=59683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}